
{"id":4446,"count":1,"description":"","link":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/","name":"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629","slug":"%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/\" \/>\n<meta property=\"og:site_name\" content=\"SMEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SMEX\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/tag\\\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\\\/\",\"url\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/tag\\\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\\\/\",\"name\":\"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/tag\\\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/tag\\\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#website\",\"url\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/\",\"name\":\"SMEX\",\"description\":\"Advancing Digital Rights\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#organization\",\"name\":\"SMEX\",\"url\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.smexold.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-010817-SMEX-Logomark-400px.png\",\"contentUrl\":\"http:\\\/\\\/www.smexold.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-010817-SMEX-Logomark-400px.png\",\"width\":401,\"height\":396,\"caption\":\"SMEX\"},\"image\":{\"@id\":\"http:\\\/\\\/www.smexold.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smex\",\"https:\\\/\\\/x.com\\\/SMEX\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/","og_locale":"ar_AR","og_type":"article","og_title":"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX","og_url":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/","og_site_name":"SMEX","twitter_card":"summary_large_image","twitter_site":"@SMEX","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/","url":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/","name":"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629 Archives - SMEX","isPartOf":{"@id":"http:\/\/www.smexold.org\/ar\/#website"},"breadcrumb":{"@id":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"http:\/\/www.smexold.org\/ar\/tag\/%d8%aa%d8%b7%d8%a8%d9%8a%d9%82%d8%a7%d8%aa-%d9%85%d8%b2%d9%8a%d9%81%d8%a9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.smexold.org\/ar\/"},{"@type":"ListItem","position":2,"name":"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u0632\u064a\u0641\u0629"}]},{"@type":"WebSite","@id":"http:\/\/www.smexold.org\/ar\/#website","url":"http:\/\/www.smexold.org\/ar\/","name":"SMEX","description":"Advancing Digital Rights","publisher":{"@id":"http:\/\/www.smexold.org\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.smexold.org\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"http:\/\/www.smexold.org\/ar\/#organization","name":"SMEX","url":"http:\/\/www.smexold.org\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/www.smexold.org\/ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.smexold.org\/wp-content\/uploads\/2021\/03\/cropped-010817-SMEX-Logomark-400px.png","contentUrl":"http:\/\/www.smexold.org\/wp-content\/uploads\/2021\/03\/cropped-010817-SMEX-Logomark-400px.png","width":401,"height":396,"caption":"SMEX"},"image":{"@id":"http:\/\/www.smexold.org\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smex","https:\/\/x.com\/SMEX"]}]}},"_links":{"self":[{"href":"http:\/\/www.smexold.org\/ar\/wp-json\/wp\/v2\/tags\/4446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.smexold.org\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.smexold.org\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.smexold.org\/ar\/wp-json\/wp\/v2\/posts?tags=4446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}